{"id":2329,"date":"2024-07-12T07:29:27","date_gmt":"2024-07-12T06:29:27","guid":{"rendered":"https:\/\/ricardochinauthor.com\/la-verdad-del-universo\/"},"modified":"2024-07-12T07:29:27","modified_gmt":"2024-07-12T06:29:27","slug":"la-verdad-del-universo","status":"publish","type":"post","link":"https:\/\/ricardochinauthor.com\/es\/la-verdad-del-universo\/","title":{"rendered":"La verdad del universo"},"content":{"rendered":"<p>La verdad del universo o Dios, como lo he vivido yo, es que ambos son una \u00fanica y misma cosa\u2026 la vida de la que todos formamos parte. No hay separaci\u00f3n\u2026 no hay un \u00abyo\u00bb ni un \u00abt\u00fa\u00bb. Todo es parte de una ecuaci\u00f3n inconcebible y existencial que el cerebro humano no llega a comprender. Podr\u00eda hacer algo como Ricardo Chin que luego afectase a las vidas de las personas m\u00e1s cercanas a m\u00ed, provocando un efecto domin\u00f3 que tocase las vidas de las personas m\u00e1s cercanas a ellas, y que conitnuase a trav\u00e9s de la interconexi\u00f3n de la existencia\u2026 y todo ello, intencionadamente. Todos damos a los dem\u00e1s las experiencias necesarias para nuestra evoluci\u00f3n aparentemente individual, que luego pasa por la conexi\u00f3n de la humanidad y el resto de energ\u00edas asociadas a ella, provocando la evoluci\u00f3n de la conciencia universal.&nbsp;<\/p><p>He tenido experiencias en mi vida que me han hecho sentir negativo, no querido, solo y con una profunda sensaci\u00f3n de desesperanza, como imagino que nos ha pasado a muchos. Me he dado cuenta de que, en esos momentos, a menudo me hac\u00eda la pregunta equivocada: \u00bfqu\u00e9 sentido tiene la vida? La pregunta que deb\u00eda estar formulando en su lugar era: \u00bfqui\u00e9n voy a ser en esta situaci\u00f3n y de d\u00f3nde viene ese sentido de ser? El universo siempre se est\u00e1 comunicando con nosotros, ya sea a trav\u00e9s de situaciones, sentimientos u otra persona, y cuando me tom\u00e9 mi tiempo para parar y estar presente, por fin pude verlo.<\/p><p>Nunca intentar\u00e9 contarle a nadie cu\u00e1l es <em>la<\/em> verdad del universo, pero s\u00ed que quiero compartir la que s\u00e9 que es <em>mi<\/em> verdad. Soy mucho m\u00e1s de lo que jam\u00e1s podr\u00e9 llegar a transmitir en este texto de mi blog, pero lo voy a intentar. Estoy en el universo, y soy del universo, por lo tanto soy una expresi\u00f3n del universo, y quiz\u00e1s la explicaci\u00f3n m\u00e1s adecuada que puedo ofrecer es que soy amor.<\/p><p>\u00bfC\u00f3mo lo s\u00e9? Pues bien, pensemos en las personas con las que he podido conectar de verdad, ya sea una pareja rom\u00e1ntica, un familiar o un amigo. Lo que ocurre es que alguien llega a mi vida; hay una reuni\u00f3n, una presentaci\u00f3n y luego quiz\u00e1s cada vez que vea a esta persona, hay una sonrisa, una risa y un sentimiento com\u00fan de afecto entre nosotros que empieza a crecer. Antes de darme cuenta, me empiezo a sentir seguro en presencia de esa persona y, cuando me siento seguro, me permito ser vulnerable y, al hacerlo, empiezo a desprenderme de las capas de coraza que normalmente llevo al interactuar con el mundo en general.&nbsp;<\/p><p>Por coraza me refiero a la falta de autenticidad, a mantener alejadas a las personas, a ponerme a la defensiva, etc., y, cuanto m\u00e1s tiempo paso con esta persona, m\u00e1s capas de protecci\u00f3n aparente se disuelven. Una vez que todas esas capas han desaparecido, lo \u00fanico que queda es qui\u00e9n soy de verdad: amor. Ah\u00ed es cuando le digo a esa persona: \u00abTe quiero\u00bb, cuando lo que quiero decir es: \u00abEh, soy amor, \u00bfte lo muestro?\u00bb. Esto me ha ayudado a entender el antiguo dicho: \u00abEn presencia de un amigo verdadero, te enamoras cada vez m\u00e1s de ti mismo\u00bb.<\/p><p>A pesar de mis intentos de expresar los atisbos de verdadero amor que he tenido, no puedo explicarlo y hacerle justicia. Podr\u00eda hablar todos los idiomas del mundo y seguir\u00eda siendo incapaz de explicarlo con palabras. Es un sentimiento que debe experimentarse y sentirse; un sentimiento que elimina el miedo, la soledad, la separaci\u00f3n y el resto de ilusiones de uno mismo.&nbsp;<\/p><p>Y cando no podemos conectar de verdad con otras personas, entonces s\u00e9 que se debe a que no nos sentimos lo suficientemente seguros como para ser vulnerables y desprendernos de las capas para exponer nuestra verdadera esencia. En el fondo, s\u00e9 que soy amor, una extensi\u00f3n del universo y de lo que quiere expresar, y solo puedo imaginarme el amor incalculable que es el universo\/Dios.<\/p>","protected":false},"excerpt":{"rendered":"<p>La verdad del universo o Dios, como lo he vivido yo, es que ambos son una \u00fanica y misma cosa\u2026 la vida de la que todos formamos parte.<\/p>\n","protected":false},"author":4,"featured_media":2294,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[116],"tags":[113,111,112],"class_list":["post-2329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sabiduria-espiritual","tag-crecimiento-espiritual","tag-ricardo-chin-es","tag-unas-palabras-de-un-completo-don-nadie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La verdad del universo - Ricardo Chin Autor<\/title>\n<meta name=\"description\" content=\"Indaga en la opini\u00f3n de Ricardo Chin sobre la verdad del universo, explorando la profunda sabidur\u00eda y la naturaleza de la existencia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La verdad del universo - Ricardo Chin Autor\" \/>\n<meta property=\"og:description\" content=\"Indaga en la opini\u00f3n de Ricardo Chin sobre la verdad del universo, explorando la profunda sabidur\u00eda y la naturaleza de la existencia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/\" \/>\n<meta property=\"og:site_name\" content=\"Ricardo Chin Autor\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T06:29:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2018\/11\/The-Universe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Chin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Chin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/\"},\"author\":{\"name\":\"Ricardo Chin\",\"@id\":\"https:\/\/ricardochinauthor.com\/#\/schema\/person\/700b0a40a902af177a7f7645dd4afca8\"},\"headline\":\"La verdad del universo\",\"datePublished\":\"2024-07-12T06:29:27+00:00\",\"dateModified\":\"2024-07-12T06:29:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/\"},\"wordCount\":712,\"publisher\":{\"@id\":\"https:\/\/ricardochinauthor.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2018\/11\/The-Universe.jpg\",\"keywords\":[\"crecimiento espiritual\",\"Ricardo Chin\",\"Unas palabras de un completo don nadie\"],\"articleSection\":[\"Sabidur\u00eda espiritual\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/\",\"url\":\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/\",\"name\":\"La verdad del universo - Ricardo Chin Autor\",\"isPartOf\":{\"@id\":\"https:\/\/ricardochinauthor.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2018\/11\/The-Universe.jpg\",\"datePublished\":\"2024-07-12T06:29:27+00:00\",\"dateModified\":\"2024-07-12T06:29:27+00:00\",\"description\":\"Indaga en la opini\u00f3n de Ricardo Chin sobre la verdad del universo, explorando la profunda sabidur\u00eda y la naturaleza de la existencia.\",\"breadcrumb\":{\"@id\":\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#primaryimage\",\"url\":\"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2018\/11\/The-Universe.jpg\",\"contentUrl\":\"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2018\/11\/The-Universe.jpg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ricardochinauthor.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La verdad del universo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ricardochinauthor.com\/#website\",\"url\":\"https:\/\/ricardochinauthor.com\/\",\"name\":\"Ricardo Chin Author\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/ricardochinauthor.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ricardochinauthor.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ricardochinauthor.com\/#organization\",\"name\":\"Ricardo Chin Autor\",\"url\":\"https:\/\/ricardochinauthor.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ricardochinauthor.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2024\/08\/logo.png\",\"contentUrl\":\"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2024\/08\/logo.png\",\"width\":400,\"height\":100,\"caption\":\"Ricardo Chin Autor\"},\"image\":{\"@id\":\"https:\/\/ricardochinauthor.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ricardochinauthor.com\/#\/schema\/person\/700b0a40a902af177a7f7645dd4afca8\",\"name\":\"Ricardo Chin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ricardochinauthor.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/aa7e2f1ac2291f593cb211babe87f82c54c0773172806fcb6d9b0765eb4365c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/aa7e2f1ac2291f593cb211babe87f82c54c0773172806fcb6d9b0765eb4365c5?s=96&d=mm&r=g\",\"caption\":\"Ricardo Chin\"},\"sameAs\":[\"https:\/\/ricardochinauthor.com\"],\"url\":\"https:\/\/ricardochinauthor.com\/es\/author\/ricardoadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La verdad del universo - Ricardo Chin Autor","description":"Indaga en la opini\u00f3n de Ricardo Chin sobre la verdad del universo, explorando la profunda sabidur\u00eda y la naturaleza de la existencia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/","og_locale":"es_ES","og_type":"article","og_title":"La verdad del universo - Ricardo Chin Autor","og_description":"Indaga en la opini\u00f3n de Ricardo Chin sobre la verdad del universo, explorando la profunda sabidur\u00eda y la naturaleza de la existencia.","og_url":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/","og_site_name":"Ricardo Chin Autor","article_published_time":"2024-07-12T06:29:27+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2018\/11\/The-Universe.jpg","type":"image\/jpeg"}],"author":"Ricardo Chin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ricardo Chin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#article","isPartOf":{"@id":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/"},"author":{"name":"Ricardo Chin","@id":"https:\/\/ricardochinauthor.com\/#\/schema\/person\/700b0a40a902af177a7f7645dd4afca8"},"headline":"La verdad del universo","datePublished":"2024-07-12T06:29:27+00:00","dateModified":"2024-07-12T06:29:27+00:00","mainEntityOfPage":{"@id":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/"},"wordCount":712,"publisher":{"@id":"https:\/\/ricardochinauthor.com\/#organization"},"image":{"@id":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#primaryimage"},"thumbnailUrl":"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2018\/11\/The-Universe.jpg","keywords":["crecimiento espiritual","Ricardo Chin","Unas palabras de un completo don nadie"],"articleSection":["Sabidur\u00eda espiritual"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/","url":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/","name":"La verdad del universo - Ricardo Chin Autor","isPartOf":{"@id":"https:\/\/ricardochinauthor.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#primaryimage"},"image":{"@id":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#primaryimage"},"thumbnailUrl":"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2018\/11\/The-Universe.jpg","datePublished":"2024-07-12T06:29:27+00:00","dateModified":"2024-07-12T06:29:27+00:00","description":"Indaga en la opini\u00f3n de Ricardo Chin sobre la verdad del universo, explorando la profunda sabidur\u00eda y la naturaleza de la existencia.","breadcrumb":{"@id":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#primaryimage","url":"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2018\/11\/The-Universe.jpg","contentUrl":"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2018\/11\/The-Universe.jpg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/ricardochinauthor.com\/the-truth-of-the-universe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ricardochinauthor.com\/es\/"},{"@type":"ListItem","position":2,"name":"La verdad del universo"}]},{"@type":"WebSite","@id":"https:\/\/ricardochinauthor.com\/#website","url":"https:\/\/ricardochinauthor.com\/","name":"Ricardo Chin Author","description":"Just another WordPress site","publisher":{"@id":"https:\/\/ricardochinauthor.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ricardochinauthor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ricardochinauthor.com\/#organization","name":"Ricardo Chin Autor","url":"https:\/\/ricardochinauthor.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ricardochinauthor.com\/#\/schema\/logo\/image\/","url":"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2024\/08\/logo.png","contentUrl":"https:\/\/ricardochinauthor.com\/wp-content\/uploads\/2024\/08\/logo.png","width":400,"height":100,"caption":"Ricardo Chin Autor"},"image":{"@id":"https:\/\/ricardochinauthor.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ricardochinauthor.com\/#\/schema\/person\/700b0a40a902af177a7f7645dd4afca8","name":"Ricardo Chin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ricardochinauthor.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/aa7e2f1ac2291f593cb211babe87f82c54c0773172806fcb6d9b0765eb4365c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aa7e2f1ac2291f593cb211babe87f82c54c0773172806fcb6d9b0765eb4365c5?s=96&d=mm&r=g","caption":"Ricardo Chin"},"sameAs":["https:\/\/ricardochinauthor.com"],"url":"https:\/\/ricardochinauthor.com\/es\/author\/ricardoadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/ricardochinauthor.com\/es\/wp-json\/wp\/v2\/posts\/2329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ricardochinauthor.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ricardochinauthor.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ricardochinauthor.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ricardochinauthor.com\/es\/wp-json\/wp\/v2\/comments?post=2329"}],"version-history":[{"count":0,"href":"https:\/\/ricardochinauthor.com\/es\/wp-json\/wp\/v2\/posts\/2329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ricardochinauthor.com\/es\/wp-json\/wp\/v2\/media\/2294"}],"wp:attachment":[{"href":"https:\/\/ricardochinauthor.com\/es\/wp-json\/wp\/v2\/media?parent=2329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ricardochinauthor.com\/es\/wp-json\/wp\/v2\/categories?post=2329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ricardochinauthor.com\/es\/wp-json\/wp\/v2\/tags?post=2329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}